{"id":496622,"date":"2022-02-23T09:33:24","date_gmt":"2022-02-23T07:33:24","guid":{"rendered":"http:\/\/games.tactic.net\/tuote\/lumo-sloth-caramel-coffe-big\/"},"modified":"2024-01-02T18:10:47","modified_gmt":"2024-01-02T16:10:47","slug":"lumo-sloth-caramel-coffe-big","status":"publish","type":"product","link":"https:\/\/games.tactic.net\/nl\/tuote\/lumo-sloth-caramel-coffe-big\/","title":{"rendered":"Lumo Stars Sloth Caramel &#038; Coffe big plush"},"content":{"rendered":"<p>Classic 15 cm. Lumo Stars zijn de zachtste en mooiste pluche knuffeldieren met grote lief kijkende ogen. Er zijn vele verschillende soorten verkrijgbaar. H\u00e9 schatjes! We vinden het leuk om nieuwe speelvrienden te krijgen, kom je bij ons spelen? Verzamel ze allemaal. Download de app op lumostars.com , verzorg en speel met je eigen Lumo Star vriendje! Leeftijd vanaf: 3+<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Classic 15 cm. Lumo Stars zijn de zachtste en mooiste pluche knuffeldieren met grote lief kijkende ogen. Er zijn vele verschillende soorten verkrijgbaar. H\u00e9 schatjes! We vinden het leuk om nieuwe speelvrienden te krijgen, kom je bij ons spelen? Verzamel ze allemaal. Download de app op lumostars.com , verzorg en speel met je eigen Lumo [&hellip;]<\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"content-type":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"product_brand":[],"product_cat":[1897],"product_tag":[491],"brand":[{"id":1022,"name":"Lumo Stars","slug":"lumo-stars_nl"}],"target-group":[],"discontinued":[],"class_list":["post-496622","product","type-product","status-publish","product_cat-big-pluche","product_tag-lumo-stars","brand-lumo-stars_nl","first","instock","taxable","shipping-taxable","product-type-simple"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Classic 15 cm. Lumo Stars zijn de zachtste en mooiste pluche knuffeldieren met grote lief kijkende ogen. Er zijn vele verschillende soorten verkrijgbaar. H\u00e9 schatjes! We vinden het leuk om nieuwe speelvrienden te krijgen, kom je bij ons spelen? Verzamel ze allemaal. Download de app op lumostars.com , verzorg en speel met je eigen Lumo\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/games.tactic.net\/nl\/tuote\/lumo-sloth-caramel-coffe-big\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"nl_NL\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Tactic Games - Board Games\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Lumo Stars Sloth Caramel &amp; Coffe big plush - Tactic Games\" \/>\n\t\t<meta property=\"og:description\" content=\"Classic 15 cm. Lumo Stars zijn de zachtste en mooiste pluche knuffeldieren met grote lief kijkende ogen. Er zijn vele verschillende soorten verkrijgbaar. H\u00e9 schatjes! We vinden het leuk om nieuwe speelvrienden te krijgen, kom je bij ons spelen? Verzamel ze allemaal. Download de app op lumostars.com , verzorg en speel met je eigen Lumo\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/games.tactic.net\/nl\/tuote\/lumo-sloth-caramel-coffe-big\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/games.tactic.net\/wp-content\/uploads\/2021\/12\/cropped-tactic.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/games.tactic.net\/wp-content\/uploads\/2021\/12\/cropped-tactic.png\" \/>\n\t\t<meta property=\"og:image:width\" content=\"150\" \/>\n\t\t<meta property=\"og:image:height\" content=\"59\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2022-02-23T07:33:24+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-01-02T16:10:47+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tacticgamesoy\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@TacticGames\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Lumo Stars Sloth Caramel &amp; Coffe big plush - Tactic Games\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Classic 15 cm. Lumo Stars zijn de zachtste en mooiste pluche knuffeldieren met grote lief kijkende ogen. Er zijn vele verschillende soorten verkrijgbaar. H\u00e9 schatjes! We vinden het leuk om nieuwe speelvrienden te krijgen, kom je bij ons spelen? Verzamel ze allemaal. Download de app op lumostars.com , verzorg en speel met je eigen Lumo\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/games.tactic.net\/wp-content\/uploads\/2021\/12\/cropped-tactic.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/games.tactic.net\\\/nl\\\/tuote\\\/lumo-sloth-caramel-coffe-big\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/games.tactic.net\\\/nl\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/games.tactic.net\\\/nl\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/games.tactic.net\\\/nl\\\/producten\\\/#listItem\",\"name\":\"Producten\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/games.tactic.net\\\/nl\\\/producten\\\/#listItem\",\"position\":2,\"name\":\"Producten\",\"item\":\"https:\\\/\\\/games.tactic.net\\\/nl\\\/producten\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/games.tactic.net\\\/nl\\\/producten\\\/speelgoed\\\/#listItem\",\"name\":\"Speelgoed\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/games.tactic.net\\\/nl\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/games.tactic.net\\\/nl\\\/producten\\\/speelgoed\\\/#listItem\",\"position\":3,\"name\":\"Speelgoed\",\"item\":\"https:\\\/\\\/games.tactic.net\\\/nl\\\/producten\\\/speelgoed\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/games.tactic.net\\\/nl\\\/producten\\\/speelgoed\\\/lumo-stars-speelgoed\\\/#listItem\",\"name\":\"Lumo Stars\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/games.tactic.net\\\/nl\\\/producten\\\/#listItem\",\"name\":\"Producten\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/games.tactic.net\\\/nl\\\/producten\\\/speelgoed\\\/lumo-stars-speelgoed\\\/#listItem\",\"position\":4,\"name\":\"Lumo Stars\",\"item\":\"https:\\\/\\\/games.tactic.net\\\/nl\\\/producten\\\/speelgoed\\\/lumo-stars-speelgoed\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/games.tactic.net\\\/nl\\\/producten\\\/speelgoed\\\/lumo-stars-speelgoed\\\/pluche\\\/#listItem\",\"name\":\"Pluche\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/games.tactic.net\\\/nl\\\/producten\\\/speelgoed\\\/#listItem\",\"name\":\"Speelgoed\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/games.tactic.net\\\/nl\\\/producten\\\/speelgoed\\\/lumo-stars-speelgoed\\\/pluche\\\/#listItem\",\"position\":5,\"name\":\"Pluche\",\"item\":\"https:\\\/\\\/games.tactic.net\\\/nl\\\/producten\\\/speelgoed\\\/lumo-stars-speelgoed\\\/pluche\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/games.tactic.net\\\/nl\\\/producten\\\/speelgoed\\\/lumo-stars-speelgoed\\\/pluche\\\/big-pluche\\\/#listItem\",\"name\":\"Big\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/games.tactic.net\\\/nl\\\/producten\\\/speelgoed\\\/lumo-stars-speelgoed\\\/#listItem\",\"name\":\"Lumo Stars\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/games.tactic.net\\\/nl\\\/producten\\\/speelgoed\\\/lumo-stars-speelgoed\\\/pluche\\\/big-pluche\\\/#listItem\",\"position\":6,\"name\":\"Big\",\"item\":\"https:\\\/\\\/games.tactic.net\\\/nl\\\/producten\\\/speelgoed\\\/lumo-stars-speelgoed\\\/pluche\\\/big-pluche\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/games.tactic.net\\\/nl\\\/tuote\\\/lumo-sloth-caramel-coffe-big\\\/#listItem\",\"name\":\"Lumo Stars Sloth Caramel &#038; Coffe big plush\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/games.tactic.net\\\/nl\\\/producten\\\/speelgoed\\\/lumo-stars-speelgoed\\\/pluche\\\/#listItem\",\"name\":\"Pluche\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/games.tactic.net\\\/nl\\\/tuote\\\/lumo-sloth-caramel-coffe-big\\\/#listItem\",\"position\":7,\"name\":\"Lumo Stars Sloth Caramel &#038; Coffe big plush\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/games.tactic.net\\\/nl\\\/producten\\\/speelgoed\\\/lumo-stars-speelgoed\\\/pluche\\\/big-pluche\\\/#listItem\",\"name\":\"Big\"}}]},{\"@type\":\"ItemPage\",\"@id\":\"https:\\\/\\\/games.tactic.net\\\/nl\\\/tuote\\\/lumo-sloth-caramel-coffe-big\\\/#itempage\",\"url\":\"https:\\\/\\\/games.tactic.net\\\/nl\\\/tuote\\\/lumo-sloth-caramel-coffe-big\\\/\",\"name\":\"Lumo Stars Sloth Caramel & Coffe big plush - Tactic Games\",\"description\":\"Classic 15 cm. Lumo Stars zijn de zachtste en mooiste pluche knuffeldieren met grote lief kijkende ogen. Er zijn vele verschillende soorten verkrijgbaar. H\\u00e9 schatjes! We vinden het leuk om nieuwe speelvrienden te krijgen, kom je bij ons spelen? Verzamel ze allemaal. Download de app op lumostars.com , verzorg en speel met je eigen Lumo\",\"inLanguage\":\"nl-NL\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/games.tactic.net\\\/nl\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/games.tactic.net\\\/nl\\\/tuote\\\/lumo-sloth-caramel-coffe-big\\\/#breadcrumblist\"},\"datePublished\":\"2022-02-23T09:33:24+02:00\",\"dateModified\":\"2024-01-02T18:10:47+02:00\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/games.tactic.net\\\/nl\\\/#organization\",\"name\":\"Tactic Games Oy\",\"description\":\"Board Games\",\"url\":\"https:\\\/\\\/games.tactic.net\\\/nl\\\/\",\"telephone\":\"+35826244144\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/games.tactic.net\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Tactic-logo.png\",\"@id\":\"https:\\\/\\\/games.tactic.net\\\/nl\\\/tuote\\\/lumo-sloth-caramel-coffe-big\\\/#organizationLogo\",\"width\":150,\"height\":59,\"caption\":\"Tactic logo\"},\"image\":{\"@id\":\"https:\\\/\\\/games.tactic.net\\\/nl\\\/tuote\\\/lumo-sloth-caramel-coffe-big\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/tacticgamesoy\",\"https:\\\/\\\/twitter.com\\\/TacticGames\",\"https:\\\/\\\/www.instagram.com\\\/tacticgames\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/@tactic_games?\"]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/games.tactic.net\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/games.tactic.net\\\/nl\\\/\",\"name\":\"Tactic Games\",\"description\":\"Board Games\",\"inLanguage\":\"nl-NL\",\"publisher\":{\"@id\":\"https:\\\/\\\/games.tactic.net\\\/nl\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Lumo Stars Sloth Caramel & Coffe big plush - Tactic Games","description":"Classic 15 cm. Lumo Stars zijn de zachtste en mooiste pluche knuffeldieren met grote lief kijkende ogen. Er zijn vele verschillende soorten verkrijgbaar. H\u00e9 schatjes! We vinden het leuk om nieuwe speelvrienden te krijgen, kom je bij ons spelen? Verzamel ze allemaal. Download de app op lumostars.com , verzorg en speel met je eigen Lumo","canonical_url":"https:\/\/games.tactic.net\/nl\/tuote\/lumo-sloth-caramel-coffe-big\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/games.tactic.net\/nl\/tuote\/lumo-sloth-caramel-coffe-big\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/games.tactic.net\/nl\/#listItem","position":1,"name":"Home","item":"https:\/\/games.tactic.net\/nl\/","nextItem":{"@type":"ListItem","@id":"https:\/\/games.tactic.net\/nl\/producten\/#listItem","name":"Producten"}},{"@type":"ListItem","@id":"https:\/\/games.tactic.net\/nl\/producten\/#listItem","position":2,"name":"Producten","item":"https:\/\/games.tactic.net\/nl\/producten\/","nextItem":{"@type":"ListItem","@id":"https:\/\/games.tactic.net\/nl\/producten\/speelgoed\/#listItem","name":"Speelgoed"},"previousItem":{"@type":"ListItem","@id":"https:\/\/games.tactic.net\/nl\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/games.tactic.net\/nl\/producten\/speelgoed\/#listItem","position":3,"name":"Speelgoed","item":"https:\/\/games.tactic.net\/nl\/producten\/speelgoed\/","nextItem":{"@type":"ListItem","@id":"https:\/\/games.tactic.net\/nl\/producten\/speelgoed\/lumo-stars-speelgoed\/#listItem","name":"Lumo Stars"},"previousItem":{"@type":"ListItem","@id":"https:\/\/games.tactic.net\/nl\/producten\/#listItem","name":"Producten"}},{"@type":"ListItem","@id":"https:\/\/games.tactic.net\/nl\/producten\/speelgoed\/lumo-stars-speelgoed\/#listItem","position":4,"name":"Lumo Stars","item":"https:\/\/games.tactic.net\/nl\/producten\/speelgoed\/lumo-stars-speelgoed\/","nextItem":{"@type":"ListItem","@id":"https:\/\/games.tactic.net\/nl\/producten\/speelgoed\/lumo-stars-speelgoed\/pluche\/#listItem","name":"Pluche"},"previousItem":{"@type":"ListItem","@id":"https:\/\/games.tactic.net\/nl\/producten\/speelgoed\/#listItem","name":"Speelgoed"}},{"@type":"ListItem","@id":"https:\/\/games.tactic.net\/nl\/producten\/speelgoed\/lumo-stars-speelgoed\/pluche\/#listItem","position":5,"name":"Pluche","item":"https:\/\/games.tactic.net\/nl\/producten\/speelgoed\/lumo-stars-speelgoed\/pluche\/","nextItem":{"@type":"ListItem","@id":"https:\/\/games.tactic.net\/nl\/producten\/speelgoed\/lumo-stars-speelgoed\/pluche\/big-pluche\/#listItem","name":"Big"},"previousItem":{"@type":"ListItem","@id":"https:\/\/games.tactic.net\/nl\/producten\/speelgoed\/lumo-stars-speelgoed\/#listItem","name":"Lumo Stars"}},{"@type":"ListItem","@id":"https:\/\/games.tactic.net\/nl\/producten\/speelgoed\/lumo-stars-speelgoed\/pluche\/big-pluche\/#listItem","position":6,"name":"Big","item":"https:\/\/games.tactic.net\/nl\/producten\/speelgoed\/lumo-stars-speelgoed\/pluche\/big-pluche\/","nextItem":{"@type":"ListItem","@id":"https:\/\/games.tactic.net\/nl\/tuote\/lumo-sloth-caramel-coffe-big\/#listItem","name":"Lumo Stars Sloth Caramel &#038; Coffe big plush"},"previousItem":{"@type":"ListItem","@id":"https:\/\/games.tactic.net\/nl\/producten\/speelgoed\/lumo-stars-speelgoed\/pluche\/#listItem","name":"Pluche"}},{"@type":"ListItem","@id":"https:\/\/games.tactic.net\/nl\/tuote\/lumo-sloth-caramel-coffe-big\/#listItem","position":7,"name":"Lumo Stars Sloth Caramel &#038; Coffe big plush","previousItem":{"@type":"ListItem","@id":"https:\/\/games.tactic.net\/nl\/producten\/speelgoed\/lumo-stars-speelgoed\/pluche\/big-pluche\/#listItem","name":"Big"}}]},{"@type":"ItemPage","@id":"https:\/\/games.tactic.net\/nl\/tuote\/lumo-sloth-caramel-coffe-big\/#itempage","url":"https:\/\/games.tactic.net\/nl\/tuote\/lumo-sloth-caramel-coffe-big\/","name":"Lumo Stars Sloth Caramel & Coffe big plush - Tactic Games","description":"Classic 15 cm. Lumo Stars zijn de zachtste en mooiste pluche knuffeldieren met grote lief kijkende ogen. Er zijn vele verschillende soorten verkrijgbaar. H\u00e9 schatjes! We vinden het leuk om nieuwe speelvrienden te krijgen, kom je bij ons spelen? Verzamel ze allemaal. Download de app op lumostars.com , verzorg en speel met je eigen Lumo","inLanguage":"nl-NL","isPartOf":{"@id":"https:\/\/games.tactic.net\/nl\/#website"},"breadcrumb":{"@id":"https:\/\/games.tactic.net\/nl\/tuote\/lumo-sloth-caramel-coffe-big\/#breadcrumblist"},"datePublished":"2022-02-23T09:33:24+02:00","dateModified":"2024-01-02T18:10:47+02:00"},{"@type":"Organization","@id":"https:\/\/games.tactic.net\/nl\/#organization","name":"Tactic Games Oy","description":"Board Games","url":"https:\/\/games.tactic.net\/nl\/","telephone":"+35826244144","logo":{"@type":"ImageObject","url":"https:\/\/games.tactic.net\/wp-content\/uploads\/2023\/11\/Tactic-logo.png","@id":"https:\/\/games.tactic.net\/nl\/tuote\/lumo-sloth-caramel-coffe-big\/#organizationLogo","width":150,"height":59,"caption":"Tactic logo"},"image":{"@id":"https:\/\/games.tactic.net\/nl\/tuote\/lumo-sloth-caramel-coffe-big\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/tacticgamesoy","https:\/\/twitter.com\/TacticGames","https:\/\/www.instagram.com\/tacticgames\/","https:\/\/www.tiktok.com\/@tactic_games?"]},{"@type":"WebSite","@id":"https:\/\/games.tactic.net\/nl\/#website","url":"https:\/\/games.tactic.net\/nl\/","name":"Tactic Games","description":"Board Games","inLanguage":"nl-NL","publisher":{"@id":"https:\/\/games.tactic.net\/nl\/#organization"}}]},"og:locale":"nl_NL","og:site_name":"Tactic Games - Board Games","og:type":"article","og:title":"Lumo Stars Sloth Caramel &amp; Coffe big plush - Tactic Games","og:description":"Classic 15 cm. Lumo Stars zijn de zachtste en mooiste pluche knuffeldieren met grote lief kijkende ogen. Er zijn vele verschillende soorten verkrijgbaar. H\u00e9 schatjes! We vinden het leuk om nieuwe speelvrienden te krijgen, kom je bij ons spelen? Verzamel ze allemaal. Download de app op lumostars.com , verzorg en speel met je eigen Lumo","og:url":"https:\/\/games.tactic.net\/nl\/tuote\/lumo-sloth-caramel-coffe-big\/","og:image":"https:\/\/games.tactic.net\/wp-content\/uploads\/2021\/12\/cropped-tactic.png","og:image:secure_url":"https:\/\/games.tactic.net\/wp-content\/uploads\/2021\/12\/cropped-tactic.png","og:image:width":150,"og:image:height":59,"article:published_time":"2022-02-23T07:33:24+00:00","article:modified_time":"2024-01-02T16:10:47+00:00","article:publisher":"https:\/\/www.facebook.com\/tacticgamesoy","twitter:card":"summary_large_image","twitter:site":"@TacticGames","twitter:title":"Lumo Stars Sloth Caramel &amp; Coffe big plush - Tactic Games","twitter:description":"Classic 15 cm. Lumo Stars zijn de zachtste en mooiste pluche knuffeldieren met grote lief kijkende ogen. Er zijn vele verschillende soorten verkrijgbaar. H\u00e9 schatjes! We vinden het leuk om nieuwe speelvrienden te krijgen, kom je bij ons spelen? Verzamel ze allemaal. Download de app op lumostars.com , verzorg en speel met je eigen Lumo","twitter:image":"https:\/\/games.tactic.net\/wp-content\/uploads\/2021\/12\/cropped-tactic.png"},"aioseo_meta_data":{"post_id":"496622","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2026-07-10 15:34:52","updated":"2026-07-10 15:34:52","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/games.tactic.net\/nl\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/games.tactic.net\/nl\/producten\/\" title=\"Producten\">Producten<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/games.tactic.net\/nl\/producten\/speelgoed\/\" title=\"Speelgoed\">Speelgoed<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/games.tactic.net\/nl\/producten\/speelgoed\/lumo-stars-speelgoed\/\" title=\"Lumo Stars\">Lumo Stars<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/games.tactic.net\/nl\/producten\/speelgoed\/lumo-stars-speelgoed\/pluche\/\" title=\"Pluche\">Pluche<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/games.tactic.net\/nl\/producten\/speelgoed\/lumo-stars-speelgoed\/pluche\/big-pluche\/\" title=\"Big\">Big<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tLumo Stars Sloth Caramel &amp; Coffe big plush\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/games.tactic.net\/nl\/"},{"label":"Producten","link":"https:\/\/games.tactic.net\/nl\/producten\/"},{"label":"Speelgoed","link":"https:\/\/games.tactic.net\/nl\/producten\/speelgoed\/"},{"label":"Lumo Stars","link":"https:\/\/games.tactic.net\/nl\/producten\/speelgoed\/lumo-stars-speelgoed\/"},{"label":"Pluche","link":"https:\/\/games.tactic.net\/nl\/producten\/speelgoed\/lumo-stars-speelgoed\/pluche\/"},{"label":"Big","link":"https:\/\/games.tactic.net\/nl\/producten\/speelgoed\/lumo-stars-speelgoed\/pluche\/big-pluche\/"},{"label":"Lumo Stars Sloth Caramel &#038; Coffe big plush","link":"https:\/\/games.tactic.net\/nl\/tuote\/lumo-sloth-caramel-coffe-big\/"}],"_links":{"self":[{"href":"https:\/\/games.tactic.net\/nl\/wp-json\/wp\/v2\/product\/496622","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/games.tactic.net\/nl\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/games.tactic.net\/nl\/wp-json\/wp\/v2\/types\/product"}],"wp:attachment":[{"href":"https:\/\/games.tactic.net\/nl\/wp-json\/wp\/v2\/media?parent=496622"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/games.tactic.net\/nl\/wp-json\/wp\/v2\/product_brand?post=496622"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/games.tactic.net\/nl\/wp-json\/wp\/v2\/product_cat?post=496622"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/games.tactic.net\/nl\/wp-json\/wp\/v2\/product_tag?post=496622"},{"taxonomy":"brand","embeddable":true,"href":"https:\/\/games.tactic.net\/nl\/wp-json\/wp\/v2\/brand?post=496622"},{"taxonomy":"target-group","embeddable":true,"href":"https:\/\/games.tactic.net\/nl\/wp-json\/wp\/v2\/target-group?post=496622"},{"taxonomy":"discontinued","embeddable":true,"href":"https:\/\/games.tactic.net\/nl\/wp-json\/wp\/v2\/discontinued?post=496622"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}